{"id":7263,"date":"2022-12-21T17:35:54","date_gmt":"2022-12-21T16:35:54","guid":{"rendered":"https:\/\/www.garbellotto.com\/?p=7263"},"modified":"2022-12-21T17:36:05","modified_gmt":"2022-12-21T16:36:05","slug":"i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego","status":"publish","type":"post","link":"https:\/\/garbellotto.com\/en\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/","title":{"rendered":"&#8220;I migliori vini affinano in Garbellotto&#8221; &#8211; In Valtellina con Emanuele Pelizzatti Perego"},"content":{"rendered":"<p>La seconda puntata di Garbellotto on Tour per il progetto \u2018I migliori vini affinano in Garbellotto\u2019, ci porta in Valtellina pi\u00f9 precisamente a Sondrio dove insieme ad Alojz Felix Jermann siamo accompagnati a scoprire la viticoltura alpina del Nebbiolo qui chiamato Chiavennasca. La cantina che ci ospita \u00e8 quella della famiglia Pelizzatti Perego dove siamo accolti da Emanuele ed Isabella, la quinta generazione dell\u2019azienda ARPEPE Mentre conosciamo meglio la realt\u00e0 Valtellinese, Emanuele ci racconta il forte legame che il pap\u00e0 Arturo aveva instaurato con Garbellotto e come le botti di Garbellotto sono la &#8220;vera casa&#8221; del loro vino. Inoltre, la famiglia ha rigenerato le botti pi\u00f9 vecchie per mantenere vive le tradizioni cosi come hanno recentemente acquistato le botti con la tecnologia NIR per ottenere il desiderato profilo aromatico nei vini. Il legno di Garbellotto rende possibile l\u2019idea di fare vino dell\u2019azienda Arpepe, siamo dunque fieri ed orgogliosi della nostra partnership con la famiglia Pelizzatti Perego. Stay tuned to follow the journey.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  style=\"display: block; margin: 0px auto;\"  id=\"_ytid_44414\"  width=\"960\" height=\"540\"  data-origwidth=\"960\" data-origheight=\"540\" src=\"https:\/\/www.youtube.com\/embed\/GDvizpggl2U?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=3&#038;loop=0&#038;rel=1&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;hl=en_US&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La seconda puntata di Garbellotto on Tour per il progetto \u2018I migliori vini affinano in Garbellotto\u2019, ci porta in Valtellina pi\u00f9 precisamente a Sondrio dove insieme ad Alojz Felix Jermann siamo accompagnati a scoprire la viticoltura alpina del Nebbiolo qui chiamato Chiavennasca. La cantina che ci ospita \u00e8 quella della famiglia Pelizzatti Perego dove siamo&#8230; <\/p>\n<div class=\"clear\"><\/div>\n<p><a href=\"https:\/\/garbellotto.com\/en\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/\" class=\"gdlr-button with-border excerpt-read-more\">Read More<\/a><\/p>\n","protected":false},"author":3,"featured_media":7264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"inline_featured_image":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[8,52],"tags":[281,282,270],"class_list":["post-7263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home-thumbnail","category-news","tag-arpepe","tag-jermann","tag-vino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.1 (Yoast SEO v27.1.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;I migliori vini affinano in Garbellotto&quot; - In Valtellina con Emanuele Pelizzatti Perego - Garbellotto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;I migliori vini affinano in Garbellotto&quot; - In Valtellina con Emanuele Pelizzatti Perego\" \/>\n<meta property=\"og:description\" content=\"La seconda puntata di Garbellotto on Tour per il progetto \u2018I migliori vini affinano in Garbellotto\u2019, ci porta in Valtellina pi\u00f9 precisamente a Sondrio dove insieme ad Alojz Felix Jermann siamo accompagnati a scoprire la viticoltura alpina del Nebbiolo qui chiamato Chiavennasca. La cantina che ci ospita \u00e8 quella della famiglia Pelizzatti Perego dove siamo... Read More\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/\" \/>\n<meta property=\"og:site_name\" content=\"Garbellotto\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/garbellottobotti\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-21T16:35:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-21T16:36:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1184\" \/>\n\t<meta property=\"og:image:height\" content=\"641\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"garbellotto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"garbellotto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/\"},\"author\":{\"name\":\"garbellotto\",\"@id\":\"https:\/\/garbellotto.com\/#\/schema\/person\/80e72ea6306a7cc86734eb3eefccdd12\"},\"headline\":\"&#8220;I migliori vini affinano in Garbellotto&#8221; &#8211; In Valtellina con Emanuele Pelizzatti Perego\",\"datePublished\":\"2022-12-21T16:35:54+00:00\",\"dateModified\":\"2022-12-21T16:36:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/\"},\"wordCount\":183,\"publisher\":{\"@id\":\"https:\/\/garbellotto.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg\",\"keywords\":[\"arpepe\",\"jermann\",\"vino\"],\"articleSection\":[\"Home Thumbnail\",\"News\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/\",\"url\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/\",\"name\":\"\\\"I migliori vini affinano in Garbellotto\\\" - In Valtellina con Emanuele Pelizzatti Perego - Garbellotto\",\"isPartOf\":{\"@id\":\"https:\/\/garbellotto.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg\",\"datePublished\":\"2022-12-21T16:35:54+00:00\",\"dateModified\":\"2022-12-21T16:36:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#primaryimage\",\"url\":\"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg\",\"contentUrl\":\"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg\",\"width\":1184,\"height\":641},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/garbellotto.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;I migliori vini affinano in Garbellotto&#8221; &#8211; In Valtellina con Emanuele Pelizzatti Perego\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/garbellotto.com\/#website\",\"url\":\"https:\/\/garbellotto.com\/\",\"name\":\"Garbellotto\",\"description\":\"L&#039;arte del Bottaio\",\"publisher\":{\"@id\":\"https:\/\/garbellotto.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/garbellotto.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/garbellotto.com\/#organization\",\"name\":\"G & P Garbellotto S.p.A.\",\"url\":\"https:\/\/garbellotto.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/garbellotto.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/garbellotto.com\/wp-content\/uploads\/2018\/03\/logo_garbellotto_header_trasp_viola.png\",\"contentUrl\":\"https:\/\/garbellotto.com\/wp-content\/uploads\/2018\/03\/logo_garbellotto_header_trasp_viola.png\",\"width\":523,\"height\":400,\"caption\":\"G & P Garbellotto S.p.A.\"},\"image\":{\"@id\":\"https:\/\/garbellotto.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/garbellottobotti\/\",\"https:\/\/www.instagram.com\/garbellottobotti\/\",\"https:\/\/www.linkedin.com\/company\/garbellottobotti\/\",\"https:\/\/www.youtube.com\/c\/GPGarbellottoSpA\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/garbellotto.com\/#\/schema\/person\/80e72ea6306a7cc86734eb3eefccdd12\",\"name\":\"garbellotto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/garbellotto.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e381c74e78c5a7a96b5c10bc27458ba1b8a144b7f1ac7c1ea5db513b468e2d99?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e381c74e78c5a7a96b5c10bc27458ba1b8a144b7f1ac7c1ea5db513b468e2d99?s=96&d=mm&r=g\",\"caption\":\"garbellotto\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\"I migliori vini affinano in Garbellotto\" - In Valtellina con Emanuele Pelizzatti Perego - Garbellotto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/","og_locale":"en_US","og_type":"article","og_title":"\"I migliori vini affinano in Garbellotto\" - In Valtellina con Emanuele Pelizzatti Perego","og_description":"La seconda puntata di Garbellotto on Tour per il progetto \u2018I migliori vini affinano in Garbellotto\u2019, ci porta in Valtellina pi\u00f9 precisamente a Sondrio dove insieme ad Alojz Felix Jermann siamo accompagnati a scoprire la viticoltura alpina del Nebbiolo qui chiamato Chiavennasca. La cantina che ci ospita \u00e8 quella della famiglia Pelizzatti Perego dove siamo... Read More","og_url":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/","og_site_name":"Garbellotto","article_publisher":"https:\/\/www.facebook.com\/garbellottobotti\/","article_published_time":"2022-12-21T16:35:54+00:00","article_modified_time":"2022-12-21T16:36:05+00:00","og_image":[{"width":1184,"height":641,"url":"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg","type":"image\/jpeg"}],"author":"garbellotto","twitter_card":"summary_large_image","twitter_misc":{"Written by":"garbellotto","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#article","isPartOf":{"@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/"},"author":{"name":"garbellotto","@id":"https:\/\/garbellotto.com\/#\/schema\/person\/80e72ea6306a7cc86734eb3eefccdd12"},"headline":"&#8220;I migliori vini affinano in Garbellotto&#8221; &#8211; In Valtellina con Emanuele Pelizzatti Perego","datePublished":"2022-12-21T16:35:54+00:00","dateModified":"2022-12-21T16:36:05+00:00","mainEntityOfPage":{"@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/"},"wordCount":183,"publisher":{"@id":"https:\/\/garbellotto.com\/#organization"},"image":{"@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#primaryimage"},"thumbnailUrl":"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg","keywords":["arpepe","jermann","vino"],"articleSection":["Home Thumbnail","News"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/","url":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/","name":"\"I migliori vini affinano in Garbellotto\" - In Valtellina con Emanuele Pelizzatti Perego - Garbellotto","isPartOf":{"@id":"https:\/\/garbellotto.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#primaryimage"},"image":{"@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#primaryimage"},"thumbnailUrl":"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg","datePublished":"2022-12-21T16:35:54+00:00","dateModified":"2022-12-21T16:36:05+00:00","breadcrumb":{"@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#primaryimage","url":"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg","contentUrl":"https:\/\/garbellotto.com\/wp-content\/uploads\/2022\/12\/perego.jpg","width":1184,"height":641},{"@type":"BreadcrumbList","@id":"https:\/\/garbellotto.com\/2022\/12\/21\/i-migliori-vini-affinano-in-garbellotto-in-valtellina-con-emanuele-pelizzatti-perego\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/garbellotto.com\/en\/"},{"@type":"ListItem","position":2,"name":"&#8220;I migliori vini affinano in Garbellotto&#8221; &#8211; In Valtellina con Emanuele Pelizzatti Perego"}]},{"@type":"WebSite","@id":"https:\/\/garbellotto.com\/#website","url":"https:\/\/garbellotto.com\/","name":"Garbellotto","description":"L&#039;arte del Bottaio","publisher":{"@id":"https:\/\/garbellotto.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/garbellotto.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/garbellotto.com\/#organization","name":"G & P Garbellotto S.p.A.","url":"https:\/\/garbellotto.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/garbellotto.com\/#\/schema\/logo\/image\/","url":"https:\/\/garbellotto.com\/wp-content\/uploads\/2018\/03\/logo_garbellotto_header_trasp_viola.png","contentUrl":"https:\/\/garbellotto.com\/wp-content\/uploads\/2018\/03\/logo_garbellotto_header_trasp_viola.png","width":523,"height":400,"caption":"G & P Garbellotto S.p.A."},"image":{"@id":"https:\/\/garbellotto.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/garbellottobotti\/","https:\/\/www.instagram.com\/garbellottobotti\/","https:\/\/www.linkedin.com\/company\/garbellottobotti\/","https:\/\/www.youtube.com\/c\/GPGarbellottoSpA\/"]},{"@type":"Person","@id":"https:\/\/garbellotto.com\/#\/schema\/person\/80e72ea6306a7cc86734eb3eefccdd12","name":"garbellotto","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/garbellotto.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e381c74e78c5a7a96b5c10bc27458ba1b8a144b7f1ac7c1ea5db513b468e2d99?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e381c74e78c5a7a96b5c10bc27458ba1b8a144b7f1ac7c1ea5db513b468e2d99?s=96&d=mm&r=g","caption":"garbellotto"}}]}},"_links":{"self":[{"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/posts\/7263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/comments?post=7263"}],"version-history":[{"count":2,"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/posts\/7263\/revisions"}],"predecessor-version":[{"id":7268,"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/posts\/7263\/revisions\/7268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/media\/7264"}],"wp:attachment":[{"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/media?parent=7263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/categories?post=7263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/garbellotto.com\/en\/wp-json\/wp\/v2\/tags?post=7263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}